{"id":12,"date":"2023-07-24T12:52:38","date_gmt":"2023-07-24T12:52:38","guid":{"rendered":"https:\/\/www.campings.com\/fr-be\/content\/?page_id=12"},"modified":"2023-07-24T12:54:42","modified_gmt":"2023-07-24T12:54:42","slug":"politique-de-confidentialite-et-cookies","status":"publish","type":"page","link":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/","title":{"rendered":"Politique de confidentialit\u00e9 et cookies"},"content":{"rendered":"<p><b>POLITIQUE DE CONFIDENTIALIT\u00c9 ET COOKIES DU SITE WWW.CAMPINGS.COM.<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab\u00a0<\/span><b>Politique de Confidentialit\u00e9<\/b><span style=\"font-weight: 400\">\u00a0\u00bb) vise \u00e0 informer les utilisateurs du site <\/span><a href=\"http:\/\/www.campings.com\"><span style=\"font-weight: 400\">www.campings.com<\/span><\/a><span style=\"font-weight: 400\"> (le \u00ab\u00a0<\/span><b>Site<\/b><span style=\"font-weight: 400\">\u00a0\u00bb) et clients (ensemble, les \u00ab\u00a0<\/span><b>Utilisateurs<\/b><span style=\"font-weight: 400\">\u00a0\u00bb) de la mani\u00e8re dont CAMPINGS.COM UNITED LTD (\u00ab\u00a0<\/span><b>CAMPINGS.COM LTD<\/b><span style=\"font-weight: 400\">\u00a0\u00bb) et les soci\u00e9t\u00e9s de son groupe, notamment CAMPINGS.COM SAS, traitent les informations se rapportant directement ou indirectement \u00e0 tout Utilisateur (les \u00ab\u00a0<\/span><b>Donn\u00e9es \u00e0 Caract\u00e8re Personnel<\/b><span style=\"font-weight: 400\">\u00a0\u00bb).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">En acc\u00e9dant et utilisant le Site, les Utilisateurs reconnaissent \u00eatre li\u00e9s par la Politique de Confidentialit\u00e9, qui peut \u00eatre modifi\u00e9e ou mise \u00e0 jour \u00e0 tout moment sans pr\u00e9avis. Toute modification ou mise \u00e0 jour sera mise en ligne sur le Site. Si les modifications de la Politique de Confidentialit\u00e9 concernent des \u00e9l\u00e9ments pour lesquels le consentement des Utilisateurs avait \u00e9t\u00e9 requis, le consentement des Utilisateurs sera de nouveau demand\u00e9.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">La Politique de Confidentialit\u00e9 forme un tout avec les CGV du Site. Les termes en majuscule ont la d\u00e9finition qui leur est donn\u00e9e dans les CGV du Site.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>TRAITEMENT DE VOS DONNEES A CARACTERE PERSONNEL<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>CONDITIONS DU TRAITEMENT DES DONN\u00c9ES \u00c0 CARACT\u00c8RE PERSONNEL<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD et CAMPINGS.COM SAS sont amen\u00e9s \u00e0 collecter et traiter les Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs du Site et des clients de CAMPINGS.COM LTD d\u00e8s lors qu\u2019ils effectuent une r\u00e9servation sur le Site.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Dans le cadre de l\u2019utilisation du Site et des R\u00e9servations qui y seraient effectu\u00e9es\u00a0:\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">CAMPINGS.COM LTD est le cocontractant des clients\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">CAMPINGS.COM SAS est l\u2019agent de CAMPINGS.COM LTD en France et g\u00e8re la relation client ainsi que le support aux Utilisateurs.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Dans ce cadre, CAMPINGS.COM LTD et CAMPINGS.COM SAS sont les responsables du traitement des Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs. CAMPINGS.COM SAS a d\u00e9sign\u00e9 un d\u00e9l\u00e9gu\u00e9 \u00e0 la protection des donn\u00e9es.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD respecte \u00e0 ce titre le R\u00e8glement G\u00e9n\u00e9ral pour la Protection des Donn\u00e9es dit \u00ab\u00a0RGPD\u00a0\u00bb ainsi le <\/span><i><span style=\"font-weight: 400\">Data Protection Act <\/span><\/i><span style=\"font-weight: 400\">de 2018, incluant le UK General Data Protection Regulation.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM SAS s\u2019engage \u00e0 respecter le RGPD ainsi que la loi n\u00b078-17 du 6 janvier 1978 relative \u00e0 l\u2019informatique, aux fichiers et aux libert\u00e9s dite \u00ab\u00a0<\/span><i><span style=\"font-weight: 400\">Informatique et Libert\u00e9s<\/span><\/i><span style=\"font-weight: 400\">\u00a0\u00bb.\u00a0 Ces l\u00e9gislations seront d\u00e9sign\u00e9es ensemble\u00a0 \u00ab\u00a0<\/span><b>R\u00e8glementation Applicable<\/b><span style=\"font-weight: 400\">\u00a0\u00bb).\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD et CAMPINGS.COM SAS, s\u2019engagent notamment \u00e0\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Respecter et assurer transparence, loyaut\u00e9 et l\u00e9galit\u00e9 dans le traitement et l&#8217;utilisation des donn\u00e9es \u00e0 caract\u00e8re personnel\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Limiter le traitement des donn\u00e9es \u00e0 caract\u00e8re personnel \u00e0 des fins pr\u00e9cises, explicites et l\u00e9gitimes\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Minimiser la collecte et le stockage des donn\u00e9es \u00e0 caract\u00e8re personnel au regard de la finalit\u00e9 du traitement\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Garantir l&#8217;exactitude des donn\u00e9es \u00e0 caract\u00e8re personnel et permettre leur effacement ou leur rectification\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Limiter la conservation des donn\u00e9es \u00e0 caract\u00e8re personnel\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Assurer la s\u00e9curit\u00e9, l&#8217;int\u00e9grit\u00e9 et la confidentialit\u00e9 des donn\u00e9es \u00e0 caract\u00e8re personnel.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>DONN\u00c9ES \u00c0 CARACT\u00c8RE PERSONNEL COLLECT\u00c9ES PAR CAMPINGS.COM<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Certaines Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont obligatoires afin de pouvoir effectuer une R\u00e9servation.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les cat\u00e9gories de Donn\u00e9es \u00e0 Caract\u00e8re Personnel collect\u00e9es par CAMPINGS.COM LTD sont les suivantes :<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">donn\u00e9es d\u2019identification du client, notamment son \u00e9tat-civil et ses adresses postales et email\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">donn\u00e9es de facturation du client\u00a0: adresse postale, R\u00e9servation, montant de la R\u00e9servation, date de paiement, etc\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">si le Client est un salari\u00e9 d\u2019un comit\u00e9 social et \u00e9conomique partenaire\u00a0: nom de l\u2019entreprise et identifiant.\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM SAS pourra collecter les Donn\u00e9es \u00e0 Caract\u00e8re Personnel suivantes\u00a0:\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Donn\u00e9es de contact du client ou des clients\u00a0: t\u00e9l\u00e9phone, adresse postale, adresse \u00e9lectronique\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Donn\u00e9es d\u2019identification du client ou des clients, ainsi que des autres participants au s\u00e9jour dont les donn\u00e9es lui auront \u00e9t\u00e9 communiqu\u00e9es par le ou les clients pour effectuer une R\u00e9servation\u00a0: \u00e9tat-civil, situation familiale\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Donn\u00e9es de facturation\u00a0: mode de paiement carte bancaire, ch\u00e8que vacances ou carte cadeaux), date de R\u00e9servation et de paiement, montant de la R\u00e9servation\u00a0;\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Si le Client est un allocataire et b\u00e9n\u00e9ficie d\u2019une aide aux vacances familles de la CAF\u00a0: num\u00e9ro d\u2019allocataire\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Si le Client est un agent public d\u00e9pendant du C.N.A.S ou du C.G.O.S\u00a0: num\u00e9ro ou identifiant CNAS ou CGOS\u00a0;\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Le cas \u00e9ch\u00e9ant, conversation t\u00e9l\u00e9phonique avec un Utilisateur ayant appel\u00e9 CAMPINGS.COM SAS, si l\u2019Utilisateur ne s\u2019y est pas oppos\u00e9.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400\">Les Utilisateurs doivent fournir \u00e0 CAMPINGS.COM LTD et CAMPINGS.COM SAS de mani\u00e8re exacte, sinc\u00e8re et v\u00e9ritable leurs Donn\u00e9es \u00e0 Caract\u00e8re Personnel ainsi que celles des participants au s\u00e9jour.<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>FINALIT\u00c9 DE LA COLLECTE DES DONN\u00c9ES \u00c0 CARACT\u00c8RE PERSONNEL<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les donn\u00e9es collect\u00e9es par CAMPINGS.COM LTD sont utilis\u00e9es dans le cadre du traitement, de l\u2019ex\u00e9cution et du suivi de la commande de l\u2019Utilisateur, les Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont collect\u00e9es et trait\u00e9es sur le fondement du contrat conclu entre l\u2019Utilisateur et CAMPINGS.COM LTD ainsi que pour la gestion comptable et financi\u00e8re des R\u00e9servations.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les donn\u00e9es collect\u00e9es par CAMPINGS.COM SAS sont utilis\u00e9es dans le cadre\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">du traitement, de l\u2019ex\u00e9cution et du suivi de la Commande de l\u2019Utilisateur, sur le fondement de son int\u00e9r\u00eat l\u00e9gitime \u00e0 fournir des services pour le compte de CAMPINGS.COM LTD, et notamment pour les fins suivantes\u00a0:\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Cr\u00e9ation et gestion, acc\u00e8s et utilisation du compte de l\u2019Utilisateur, si l\u2019Utilisateur a cr\u00e9\u00e9 un compte\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Traitement des demandes et des r\u00e9servations de l\u2019Utilisateur\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Facturation pour le compte de CAMPINGS.COM LTD\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Suivi de l\u2019ex\u00e9cution et bonne ex\u00e9cution de la commande ;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">dans le cadre de la gestion des prospects et des Utilisateurs, les Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont collect\u00e9es et trait\u00e9es sur le fondement du consentement de l\u2019Utilisateur, pour les raisons suivantes\u00a0:<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">sollicitation commerciale r\u00e9alis\u00e9e par CAMPINGS.COM pour des produits ou services analogues par envoi de newsletters, SMS, courrier ou via les r\u00e9seaux sociaux\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">recueil d\u2019avis-client ;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">dans le cadre d\u2019activit\u00e9s li\u00e9es au fonctionnement des services propos\u00e9s par CAMPINGS.COM LTD et CAMPINGS.COM SAS, les Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont collect\u00e9es et trait\u00e9es sur le fondement de l\u2019int\u00e9r\u00eat l\u00e9gitime de CAMPINGS.COM SAS, pour les objectifs suivants\u00a0:\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">am\u00e9lioration des services propos\u00e9s par CAMPINGS.COM LTD et CAMPINGS.COM SAS\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">d\u00e9tection des activit\u00e9s frauduleuses ou des atteintes \u00e0 la s\u00e9curit\u00e9 des services assur\u00e9s par CAMPINGS.COM LTD et CAMPINGS.COM SAS et poursuites \u00e9ventuelles\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">op\u00e9rations d\u2019analyses, statistiques et reporting\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">r\u00e9ponse \u00e0 une demande de communication l\u00e9gale.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>TRANSFERT DES DONN\u00c9ES \u00c0 CARACT\u00c8RE PERSONNEL DES UTILISATEURS<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD et CAMPINGS.COM SAS peuvent transmettre les Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs \u00e0 plusieurs destinataires et notamment\u00a0:\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">aux collaborateurs de CAMPINGS.COM UNITED LTD (situ\u00e9 sur le territoire du Royaume-Uni, lequel dispose d\u2019une d\u00e9cision d\u2019ad\u00e9quation permettant de garantir un niveau de protection des donn\u00e9es ad\u00e9quat) et de CAMPINGS.COM SAS et dont l\u2019intervention est n\u00e9cessaire pour l\u2019accomplissement des prestations ou le suivi de la relation client\u00e8le (service marketing et commercial)\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">aux Partenaires pour l\u2019organisation de la R\u00e9servation. A ce titre, les Donn\u00e9es \u00e0 Caract\u00e8re Personnel pourront \u00eatre transf\u00e9r\u00e9es en dehors de l\u2019Union Europ\u00e9enne seulement dans l\u2019hypoth\u00e8se o\u00f9 le Partenaire est lui-m\u00eame situ\u00e9 en dehors de l\u2019Union Europ\u00e9enne\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">\u00e0 la CAF, pour la prise en compte de l\u2019aide aux vacances famille lors de la r\u00e9servation du s\u00e9jour\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">\u00e0 Pledg, partenaire de CAMPINGS.COM SAS, permettant de proposer aux Utilisateurs une avance de paiement ou un paiement diff\u00e9r\u00e9 ou en plusieurs fois. Dans ces deux derniers cas, Pledg et Campings.com sont responsables conjoints du traitement. Les grandes lignes de leur accord sont fournies en Annexe\u00a0;<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">\u00a0\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">aux sous-traitants mandat\u00e9s par CAMPINGS.COM SAS, ne pouvant disposer des donn\u00e9es \u00e0 d\u2019autres fins que celles mentionn\u00e9es ci-dessus\u00a0:\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Google Cloud Platform, qui est l\u2019h\u00e9bergeur du Site et dont les serveurs sont situ\u00e9s au sein de l\u2019Union Europ\u00e9enne\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Zendesk, qui est l\u2019\u00e9diteur de la solution d\u2019assistance et de support client utilis\u00e9 par CAMPINGS.COM SAS. A ce titre, les Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont susceptibles d\u2019\u00eatre transf\u00e9r\u00e9es dans des pays tiers \u00e0 l\u2019Union Europ\u00e9enne, notamment les Etats-Unis. Afin de garantir la protection des Donn\u00e9es \u00e0 Caract\u00e8re Personnel, CAMPINGS.COM met en place des clauses contractuelles types de la Commission Europ\u00e9enne ;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">SMILE, qui g\u00e8re le support client pour le compte de CAMPINGS.COM SAS. A ce titre, les Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont susceptibles d\u2019\u00eatre transf\u00e9r\u00e9es en Tunisie. Afin de garantir la protection des Donn\u00e9es \u00e0 Caract\u00e8re Personnel, CAMPINGS.COM met en place des clauses contractuelles types de la Commission Europ\u00e9enne\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">EMARSYS, qui est le prestataire d\u2019envoi d\u2019emails de CAMPINGS.COM SAS, situ\u00e9 au sein de l\u2019Union Europ\u00e9enne\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Trust Pilot, qui recueille les avis des Utilisateurs, situ\u00e9 au sein de l\u2019Union Europ\u00e9enne\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Spot-Hit, qui est le prestataire d\u2019envoi de SMS, et dont les serveurs sont situ\u00e9s au sein de l\u2019Union Europ\u00e9enne\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">les prestataires de paiement de CAMPINGS.COM SAS, tels que Paypal, si l\u2019Utilisateur d\u00e9tient un compte aupr\u00e8s de cette soci\u00e9t\u00e9 ou Ayden, Verifone, dont les serveurs sont situ\u00e9s au sein de l\u2019Union Europ\u00e9enne<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Chacun des intervenants, charg\u00e9 de traiter les donn\u00e9es pour le compte de CAMPINGS.COM SAS et CAMPINGS.COM LTD, pr\u00e9sente des garanties suffisantes permettant de r\u00e9pondre aux exigences l\u00e9gislatives et r\u00e9glementaires.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD et CAMPINGS.COM SAS s\u2019engagent \u00e0 ne pas communiquer, c\u00e9der ou transf\u00e9rer les Donn\u00e9es \u00e0 Caract\u00e8re Personnel \u00e0 des tiers sans le consentement des Utilisateurs, hormis le cas o\u00f9, elles devraient \u00eatre communiqu\u00e9es aux autorit\u00e9s judiciaires et administratives sur r\u00e9quisitions l\u00e9gales.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>DROITS DES UTILISATEURS SUR LEURS DONN\u00c9ES A CARACTERE PERSONNEL<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Conform\u00e9ment \u00e0 la R\u00e9glementation Applicable, les Utilisateurs, ainsi que les autres participants au s\u00e9jour objet de la R\u00e9servation, peuvent exercer les droits suivants sur les Donn\u00e9es \u00e0 Caract\u00e8re Personnel les concernant, dans les conditions et limites pr\u00e9vues par la R\u00e8glementation Applicable\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">droit d\u2019acc\u00e8s, de rectification, et d\u2019effacement des donn\u00e9es\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">droit de limitation du traitement et d\u2019opposition au traitement, y compris en cas de prospection commerciale\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">droit \u00e0 la portabilit\u00e9 des donn\u00e9es\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">droit de retirer son consentement \u00e0 tout moment, lorsqu\u2019il avait \u00e9t\u00e9 donn\u00e9 \u00e0 CAMPINGS.COM, \u00e9tant pr\u00e9cis\u00e9 que tout traitement ant\u00e9rieur des Donn\u00e9es \u00e0 Caract\u00e8re Personnel demeurera licite\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">droit pour le client de communiquer ses directives relatives \u00e0 la conservation, \u00e0 l\u2019effacement et \u00e0 la communication de ses Donn\u00e9es \u00e0 Caract\u00e8re Personnel apr\u00e8s son d\u00e9c\u00e8s\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">introduire une r\u00e9clamation aupr\u00e8s de la Commission Nationale de l\u2019Informatique et des Libert\u00e9s, de l\u2019<\/span><i><span style=\"font-weight: 400\">Information Commissioner Officer<\/span><\/i><span style=\"font-weight: 400\"> au Royaume-Uni ou de l\u2019autorit\u00e9 de protection des donn\u00e9es de son pays.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Pour toute question relative \u00e0 la protection des Donn\u00e9es \u00e0 Caract\u00e8re Personnel ou pour exercer leurs droits, les Utilisateurs peuvent \u00e9crire \u00e0 l\u2019adresse postale suivante\u00a0: CAMPINGS.COM SAS \u2013 18-20 rue du Faubourg du Temple 75541 PARIS CEDEX 11 France, ou \u00e0 l&#8217;adresse email\u00a0: <\/span><a href=\"mailto:dpo@campings.com\"><span style=\"font-weight: 400\">dpo@campings.com<\/span><\/a><span style=\"font-weight: 400\">, responsable de la protection des donn\u00e9es.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Conform\u00e9ment \u00e0 la R\u00e8glementation Applicable, CAMPINGS.COM SAS et CAMPINGS.COM LTD disposeront d\u2019un mois pour r\u00e9pondre \u00e0 toute demande, sous r\u00e9serve d\u2019une \u00e9ventuelle prolongation, et se r\u00e9servent le droit de s\u2019opposer \u00e0 toute demande consid\u00e9r\u00e9e comme abusive en raison de son caract\u00e8re r\u00e9p\u00e9titif.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les Utilisateurs sont inform\u00e9s qu\u2019ils peuvent \u00e9galement modifier leurs donn\u00e9es en se connectant \u00e0 leur compte client.<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>PROTECTION, S\u00c9CURIT\u00c9 ET CONSERVATION DES DONN\u00c9ES \u00c0 CARACT\u00c8RE PERSONNEL<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD et CAMPINGS.COM SAS s\u2019engagent \u00e0 assurer la protection des Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs par la mise en place de mesures techniques et organisationnelles appropri\u00e9es afin notamment d\u2019emp\u00eacher qu\u2019elles soient d\u00e9form\u00e9es, endommag\u00e9es ou que des tiers non autoris\u00e9s y aient acc\u00e8s.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM LTD et CAMPINGS.COM SAS s\u2019engagent \u00e0 veiller \u00e0 ce que cette protection soit apport\u00e9e par toute personne susceptible de r\u00e9aliser un traitement au titre des finalit\u00e9s ci-dessous d\u00e9crites sur les donn\u00e9es personnelles.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">En cas de violation de la s\u00e9curit\u00e9 entra\u00eenant de mani\u00e8re accidentelle ou illicite, la destruction, la perte, l&#8217;alt\u00e9ration, la divulgation non autoris\u00e9e de donn\u00e9es \u00e0 caract\u00e8re personnel transmises ou l&#8217;acc\u00e8s non autoris\u00e9 \u00e0 de telles donn\u00e9es et selon l\u2019entit\u00e9 qui subit la violation\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">CAMPINGS.COM LTD notifiera la violation des donn\u00e9es \u00e0 <\/span><i><span style=\"font-weight: 400\">l\u2019Information Commissioner Officer<\/span><\/i><span style=\"font-weight: 400\"> au Royaume-Uni dans les 72 heures ainsi qu&#8217;\u00e0 la personne concern\u00e9e par le traitement, s&#8217;il existe un risque \u00e9lev\u00e9 pour ses Donn\u00e9es \u00e0 Caract\u00e8re Personnel\u00a0;\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">CAMPINGS.COM SAS notifiera la violation des donn\u00e9es \u00e0 la Commission Nationale de l\u2019Informatique et des Libert\u00e9s dans les 72 heures ainsi qu\u2019\u00e0 la personne concern\u00e9e par le traitement, s\u2019il existe un risque \u00e9lev\u00e9 pour ses Donn\u00e9es \u00e0 Caract\u00e8re Personnel.\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Sauf dispositions l\u00e9gales imposant une dur\u00e9e de conservation sp\u00e9cifique, CAMPINGS.COM SAS conserve les Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">jusqu\u2019\u00e0 5 ans apr\u00e8s une R\u00e9servation\u00a0;\u00a0<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">jusqu\u2019\u00e0 3 ans \u00e0 compter du dernier contact depuis l\u2019utilisation du formulaire de contact\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">jusqu\u2019\u00e0 3 ans \u00e0 compter de la mise en ligne de l\u2019avis ou jusqu\u2019\u00e0 ce que l\u2019avis soit retir\u00e9 du Site\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">pour le compte client, jusqu\u2019\u00e0 2 ans \u00e0 compter de son inactivit\u00e9.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les donn\u00e9es n\u00e9cessaires au respect d\u2019une obligation l\u00e9gale (preuve, paiement etc.) sont conserv\u00e9es conform\u00e9ment aux dispositions en vigueur et selon la loi locale applicable.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>POLITIQUE DE COOKIES<\/b><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>QU\u2019EST-CE QU\u2019UN COOKIE\u00a0?<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Un cookie est un fichier pouvant \u00eatre enregistr\u00e9 sur le disque dur du terminal de l\u2019Utilisateur lorsqu\u2019il consulte le Site. Ces petits fichiers peuvent contenir, par exemple, la langue du navigateur, le panier d\u2019achat de l\u2019Utilisateur et ses pr\u00e9f\u00e9rences.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM SAS d\u00e9pose des cookies sur les terminaux de l\u2019Utilisateur afin de lui permettre de naviguer dans des conditions optimales sur le Site, d\u2019enregistrer son profil et de restaurer ses pr\u00e9f\u00e9rences lorsqu\u2019il se connecte via son terminal habituel, ou de r\u00e9aliser des statistiques.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>COOKIES UTILIS\u00c9S PAR CAMPINGS.COM SAS<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM SAS utilise des cookies :\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">de navigation<\/span><span style=\"font-weight: 400\">, qui sont n\u00e9cessaires au bon fonctionnement technique du Site car ils permettent d&#8217;optimiser l&#8217;affichage du contenu depuis chaque terminal\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">fonctionnels<\/span><span style=\"font-weight: 400\">, qui ne sont pas indispensables au bon fonctionnement du Site mais optimisent l\u2019exp\u00e9rience sur le Site en permettant de d\u2019identifier les Utilisateurs, d\u2019enregistrer leur langue et de retrouver leur panier\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Campings.com utilise une solution tierce pour vous permettre d\u2019autoriser, refuser ou param\u00e9trer les cookies. Les cookies suivants sont utilis\u00e9s\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-weight: 400\">Nom du fournisseur<\/span><\/td>\n<td><span style=\"font-weight: 400\">Nom des cookies<\/span><\/td>\n<td><span style=\"font-weight: 400\">Finalit\u00e9s<\/span><\/td>\n<td><span style=\"font-weight: 400\">Dur\u00e9e<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Axeptio<\/span><\/td>\n<td><span style=\"font-weight: 400\">&#8216;axeptio_all_vendors, axeptio_authorized_vendors, axeptio_cookies<\/span><\/td>\n<td><span style=\"font-weight: 400\">Conserver vos pr\u00e9f\u00e9rences en mati\u00e8re de cookies<\/span><\/td>\n<td><span style=\"font-weight: 400\">12 mois<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">analytiques et de mesures d\u2019audience<\/span><span style=\"font-weight: 400\">, qui permettent de suivre la navigation des Utilisateurs \u00e0 des fins d&#8217;optimisation\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-weight: 400\">Nom du fournisseur<\/span><\/td>\n<td><span style=\"font-weight: 400\">Nom des cookies<\/span><\/td>\n<td><span style=\"font-weight: 400\">Finalit\u00e9s<\/span><\/td>\n<td><span style=\"font-weight: 400\">Dur\u00e9e<\/span><\/td>\n<\/tr>\n<tr>\n<td rowspan=\"2\"><span style=\"font-weight: 400\">Google Analytics<\/span><\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=fr\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">FPAU , FPID , FPLC<\/span><\/td>\n<td rowspan=\"2\"><span style=\"font-weight: 400\">Groupe de cookies utilis\u00e9s pour permettre de comprendre comment les Utilisateurs utilise et interagissent avec le Site, et pour am\u00e9liorer le Site.<\/span><\/td>\n<td><span style=\"font-weight: 400\">3 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">_ga, _gat, _gcl_au , _gid<\/span><\/td>\n<td><span style=\"font-weight: 400\">1 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Content Square<\/span><\/p>\n<p><a href=\"https:\/\/contentsquare.com\/fr-fr\/privacy-center\/privacy-policy\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">_cs_c, _cs_id, _cs_mk_ga, _cs_root-domain, _cs_s<\/span><\/td>\n<td><span style=\"font-weight: 400\">Groupe de cookies permettant de contr\u00f4ler et d\u2019am\u00e9liorer les performances du Site<\/span><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">de publicit\u00e9<\/span><b>, <\/b><span style=\"font-weight: 400\">qui permettent de collecter des donn\u00e9es sur la performance et l\u2019exposition des compagnes publicitaires et de diffuser de la publicit\u00e9 aux Utilisateurs.<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">La liste des cookies est la suivante\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<table>\n<tbody>\n<tr>\n<td><span style=\"font-weight: 400\">Nom du fournisseur<\/span><\/td>\n<td><span style=\"font-weight: 400\">Nom des cookies<\/span><\/td>\n<td><span style=\"font-weight: 400\">Finalit\u00e9s<\/span><\/td>\n<td><span style=\"font-weight: 400\">Dur\u00e9e<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Google Analytics<\/span><\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=fr\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">Ga, Gid, 1P_JAR, CONSENT, NID<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de distinguer les visiteurs uniques sur le site en attribuant un identifiant unique pour chaque visiteur.<\/span><\/p>\n<p><span style=\"font-weight: 400\">Groupe de cookies utilis\u00e9s pour cr\u00e9er des statistiques et connaitre les taux de conversion<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Google Ads<\/span><\/p>\n<p><a href=\"https:\/\/policies.google.com\/privacy?hl=fr\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">DSID, NID, __Secure-3PAPISID, __Secure-3PSID, __Secure-3PSIDCC<\/span><\/td>\n<td><span style=\"font-weight: 400\">Groupe de cookies permettant de suivre les performances des campagnes Google Ads.<\/span><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Bing<\/span><\/p>\n<p><a href=\"https:\/\/privacy.microsoft.com\/fr-fr\/privacystatement\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">_uetvid , _uetsid , _uetmsclkid , MUID , MUIDB , SRCHD , SRCHHPGUSR , SRCHUID , SRCHUSR , SUID , _EDGE_S , _HVPN , _RWBF , _SS , _UR , dsc , ipv6<\/span><\/td>\n<td><span style=\"font-weight: 400\">Groupe de cookies permettant de suivre les performances des campagnes Bing Ads.<\/span><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Wisepop<\/span><\/p>\n<p><a href=\"https:\/\/support.wisepops.com\/article\/chyhkm9j7z-data-and-cookie-policy\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">wisepops, wisepops_session, wisepops_visits<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet d\u2019envoyer des campagnes cibl\u00e9es aux Utilisateurs par l\u2019interm\u00e9diaire de pop-ups, notifications ou bandeaux.<\/span><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Advertise Me<\/span><\/p>\n<p><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">R\u00e9gie pour diffuser les messages publicitaires<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Criteo<\/span><\/p>\n<p><a href=\"https:\/\/www.criteo.com\/fr\/privacy\/how-we-use-your-data\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">uid, optout, zdi, eid, opt, r.ack, cto_bundle, cto_optout, criteo_cookie_perm, cto_clc, cto_axid, cto_pxsig, criteo_write_test, cto_tld_test, criteo_localstorage_check, browser_data<\/span><\/p>\n<p><span style=\"font-weight: 400\">uid CMID, CMPRO, CMPS, CMRUM3, CMST\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/td>\n<td><span style=\"font-weight: 400\">Groupe de cookies permettant de recibler les Utilisateurs avec des banni\u00e8res publicitaires et de suivre les performances des campagnes publicitaires de Criteo.<\/span><\/td>\n<td><span style=\"font-weight: 400\">Entre 1 jour et 13 mois.<\/span><\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Emarsys<\/span><\/p>\n<p><a href=\"https:\/\/emarsys.com\/privacy-policy\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">&#8216;scarab.visitor, scarab.profile, cdv,\u00a0 s, xp<\/span><\/td>\n<td><span style=\"font-weight: 400\">Nous permet de vous envoyer des emails personnalis\u00e9s<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Facebook Pixel<\/span><\/p>\n<p><a href=\"https:\/\/www.facebook.com\/privacy\/explanation\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">Fbp,<\/span> <span style=\"font-weight: 400\">datr, dpr, fr, sb,<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de fournir des publicit\u00e9s plus pertinentes sur Facebook<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Officiel des Vacances<\/span><\/p>\n<p><a href=\"https:\/\/www.officiel-des-vacances.com\/page-protection-des-infos-personnelles-et-utilisation-des-cookies\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Statistique et suivi des conversions Officiel des Vacances<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Remailme<\/span><\/p>\n<p><a href=\"https:\/\/remailme.fr\/politique-confidentialite\/#:~:text=ReMailMe%20ne%20conserve%20pas%20vos,de%20base%20d'emails).\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Personnalise les messages publicitaires<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Squadata<\/span><\/p>\n<p><a href=\"blank\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">sqd_nwvst, sqd_vst<\/span><\/p>\n<p><span style=\"font-weight: 400\">ecdstpds1, livraison, capping<\/span><\/td>\n<td><span style=\"font-weight: 400\">Personnalise les messages publicitaires<\/span><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Trustpilot<\/span><\/p>\n<p><a href=\"https:\/\/fr.legal.trustpilot.com\/for-reviewers\/end-user-privacy-terms\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">OptanonAlertBoxClosed, OptanonConsent<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de r\u00e9colter des avis clients<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Toocamp<\/span><\/p>\n<p><a href=\"https:\/\/www.toocamp.com\/notre-charte.html\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">toocamp_tracking<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de cr\u00e9er des statistiques et suivi des taux de conversation de Toocamp<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Yahoo<\/span><\/p>\n<p><a href=\"https:\/\/legal.yahoo.com\/ie\/en\/yahoo\/privacy\/cookies\/index.html\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">A3 , IDSYNC<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">12 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Affilae<\/span><\/p>\n<p><a href=\"https:\/\/affilae.com\/en\/privacy-cookie-policy\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">_affilae61448ddf0830fc5fb0bd1ebc<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de suivre les performances des campagnes d\u2019affiliation<\/span><\/td>\n<td><span style=\"font-weight: 400\">1 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Daisycon<\/span><\/p>\n<p><a href=\"https:\/\/www.daisycon.com\/en\/cookies\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">PHPSESSID, DCI, PDC, ci_{program_ID} , ca_{program_ID} , si_{program_ID}<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de suivre les performances des campagnes de publicit\u00e9<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Tradetracker<\/span><\/p>\n<p><a href=\"https:\/\/tradetracker.com\/gb\/privacy-policy\/how-we-use-cookies\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Permet de suivre les performances des campagnes de publicit\u00e9<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Taboola<\/span><\/p>\n<p><a href=\"https:\/\/www.taboola.com\/fr\/policies\/privacy-policy-fr\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Permet de suivre les performances des campagnes de publicit\u00e9<\/span><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Tradedoubler<\/span><\/p>\n<p><a href=\"https:\/\/www.tradedoubler.com\/fr\/privacy-policy\/#:~:text=The%20overall%20purpose%20to%20collect,as%20profiling%20or%20retargeting%20etc.\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Permet de suivre les performances des campagnes de publicit\u00e9<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Wonderpush<\/span><\/p>\n<p><a href=\"https:\/\/www.wonderpush.com\/policies\/privacy\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Permet de vous envoyer des notifications et messages personnalis\u00e9s<\/span><\/td>\n<td><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Krxd.net<\/span><\/td>\n<td><span style=\"font-weight: 400\">_kuid<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">6 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Media.net<\/span><\/td>\n<td><span style=\"font-weight: 400\">data-c , data-c-ts , visitor-id<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">1 \u00e0 12 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">mediarithmics<\/span><\/p>\n<p><a href=\"https:\/\/www.mediarithmics.io\/legal\/data-policy\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">mics_lts , mics_uaid , mics_vid<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">Dur\u00e9e de la session<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Mediavine<\/span><\/p>\n<p><a href=\"https:\/\/www.mediavine.com\/privacy-policy\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">am_tokens , am_tokens_eu-v1 , am_tokens_eu-v1, mv_tokens , mv_tokens_eu-v1<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">2 semaines<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Pubmatic<\/span><\/p>\n<p><a href=\"https:\/\/pubmatic.com\/legal\/platform-cookie-policy\/\"><span style=\"font-weight: 400\">Politique de confidentialit\u00e9<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">KRTBCOOKIE_97 , PugT<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">1 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">Rlcdn<\/span><\/td>\n<td><span style=\"font-weight: 400\">&#8216;pxrc , rlas3<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">1 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">bidswitch<\/span><\/td>\n<td><span style=\"font-weight: 400\">c , tuuid , tuuid_lu<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">12 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><a href=\"http:\/\/360yield.com\/\"><span style=\"font-weight: 400\">360yield.com<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">tuuid , tuuid_lu , um , umeh<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">3 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><a href=\"http:\/\/cloud-media.fr\/\"><span style=\"font-weight: 400\">cloud-media.fr<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">l_id<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><a href=\"http:\/\/doubleclick.net\/\"><span style=\"font-weight: 400\">doubleclick.net<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">IDE<\/span><\/td>\n<td><span style=\"font-weight: 400\">Ces cookies permettent de pr\u00e9senter des offres et informations adapt\u00e9es \u00e0 vos centres d\u2019int\u00e9r\u00eats lors de la navigation sur Internet.<\/span><\/td>\n<td><span style=\"font-weight: 400\">13 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><a href=\"http:\/\/recommender.scarabresearch.com\/\"><span style=\"font-weight: 400\">recommender.scarabresearch.com<\/span><\/a><\/td>\n<td><span style=\"font-weight: 400\">cdv , s , xp<\/span><\/td>\n<td><\/td>\n<td><span style=\"font-weight: 400\">12 mois<\/span><\/td>\n<\/tr>\n<tr>\n<td><span style=\"font-weight: 400\">demdex<\/span><\/td>\n<td><span style=\"font-weight: 400\">demdex , dpm<\/span><\/td>\n<td><span style=\"font-weight: 400\">Permet de suivre les performances des publicit\u00e9s<\/span><\/td>\n<td><span style=\"font-weight: 400\">6 mois<\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les Utilisateurs peuvent accepter ou refuser le d\u00e9p\u00f4t de cookies sur leur terminal gr\u00e2ce au bandeau pr\u00e9vu \u00e0 cet effet lorsqu\u2019ils naviguent sur le Site.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM SAS ne conserve pas de cookies permettant de tracer des Utilisateurs ou d\u2019obtenir des adresses IP au-del\u00e0 de treize (13) mois apr\u00e8s le premier d\u00e9p\u00f4t dans le terminal des Utilisateurs. En tout \u00e9tat de cause, CAMPINGS.COM SAS sollicitera de nouveau le consentement des Utilisateurs apr\u00e8s un d\u00e9lai de six (6) mois.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les Utilisateurs peuvent \u00e0 tout moment supprimer les cookies \u00e0 partir de leur logiciel de navigation et le configurer afin de s\u2019opposer \u00e0 leur enregistrement sur leur terminal.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">CAMPINGS.COM SAS invite les Utilisateurs \u00e0 se reporter au fichier d\u2019aide du logiciel de navigation pour \u00e9tablir la configuration appropri\u00e9e. La navigation sur le Site sans acceptation des cookies pourra \u00eatre d\u00e9grad\u00e9e.<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><b>DONN\u00c9ES DE TRAFIC<\/b><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les donn\u00e9es de trafic sont g\u00e9n\u00e9r\u00e9es lorsque que le terminal est connect\u00e9 \u00e0 l\u2019internet et au Site.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Ces donn\u00e9es peuvent \u00eatre utilis\u00e9es dans un but statistique afin de proc\u00e9der \u00e0 des analyses de fr\u00e9quentation du Site et de l\u2019am\u00e9liorer en l\u2019adaptant \u00e0 leurs besoins. Les donn\u00e9es de trafic ne sont jamais exploit\u00e9es nominativement par CAMPINGS.COM SAS.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><b>ANNEXE \u2013 GRANDES LIGNES DE L\u2019ACCORD CONCLU ENTRE CAMPINGS.COM ET PLEDG<\/b><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Campings.com propose aux Utilisateurs un paiement en diff\u00e9r\u00e9 ou en plusieurs fois.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Pour cela, Campings.com a conclu un partenariat avec la soci\u00e9t\u00e9 Pledg, qui a d\u00e9velopp\u00e9 une solution permettant de proposer des paiements en plusieurs fois ou de fa\u00e7on diff\u00e9r\u00e9.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Dans ce cadre, Campings.com et Pledg r\u00e9alisent un traitement conjoint des Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs. A cette fin, et conform\u00e9ment \u00e0 la R\u00e8glementation Applicable, Campings.com et Pledg ont conclu un accord de responsabilit\u00e9 conjointe dont les Utilisateurs trouveront les grandes lignes ci-dessous.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Pleg et Campings.com collectent les Donn\u00e9es \u00e0 Caract\u00e8re Personnel des Utilisateurs suivantes\u00a0: informations relatives \u00e0 l\u2019identit\u00e9 de l\u2019Utilisateur, le prix de son s\u00e9jour, ses coordonn\u00e9es bancaires ainsi que la date et les \u00e9ch\u00e9ances de paiement.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les Donn\u00e9es \u00e0 Caract\u00e8re Personnel sont trait\u00e9es par Campings.com et Pledg afin de\u00a0:<\/span><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">g\u00e9rer l\u2019encaissement et le recouvrement du prix de la Commande et leurs relations avec les Utilisateurs (base l\u00e9gale\u00a0: ex\u00e9cution du contrat)\u00a0; et<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">respecter leurs obligations l\u00e9gales et r\u00e8glementaires (base l\u00e9gale\u00a0: obligations l\u00e9gales r\u00e9sultant notamment du Code de Commerce et du Code Mon\u00e9taire et Financier)\u00a0;<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400\"><span style=\"font-weight: 400\">Pledg peut r\u00e9aliser un filtrage et scoring des Utilisateurs pour \u00e9valuer le risque cr\u00e9dit d\u2019un Utilisateur (base l\u00e9gale\u00a0: ex\u00e9cution du contrat entre l\u2019Utilisateur et Pledg).<\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Campings.com et Pledg s\u2019engagent \u00e0 mettre en \u0153uvre les mesures de s\u00e9curit\u00e9 techniques et organisationnelles afin d\u2019assurer la confidentialit\u00e9 des Donn\u00e9es \u00e0 Caract\u00e8re Personnel et emp\u00eacher qu\u2019elles ne soient d\u00e9form\u00e9es, endommag\u00e9es ou d\u00e9truites, ou qu\u2019un tiers non autoris\u00e9 y acc\u00e8de.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les Utilisateurs disposent des droits suivants\u00a0: le droit d\u2019acc\u00e9der, de modifier et de demander la suppression de des Donn\u00e9es \u00e0 Caract\u00e8re Personnel, le droit d\u2019en obtenir la communication dans un format structur\u00e9 et lisible (sauf emp\u00eachement l\u00e9gitime). Les Utilisateurs peuvent \u00e9galement demander la limitation du traitement de leurs Donn\u00e9es \u00e0 Caract\u00e8re Personnel, ou s\u2019opposer \u00e0 un traitement, y compris en cas de profilage.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Les Utilisateurs peuvent introduire une r\u00e9clamation aupr\u00e8s de la CNIL et d\u00e9finir des directives relatives \u00e0 leur testament num\u00e9rique.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">Dans le cadre du traitement conjoint mis en \u0153uvre par Pledg et Campings.com, Campings.com est le point de contact des Utilisateurs pour obtenir des informations quant \u00e0 ce traitement et\/ou pour que les Utilisateurs exercent leurs droits.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400\">A cette fin, les Utilisateurs peuvent \u00e9crire \u00e0 Campings.com \u00e0 l\u2019adresse postale suivante\u00a0: CAMPINGS.COM \u2013 18-20 rue du Faubourg du Temple 75541 PARIS CEDEX 11 France, ou \u00e0 l&#8217;adresse email\u00a0: <\/span><a href=\"mailto:dpo@campings.com\"><span style=\"font-weight: 400\">dpo@campings.com<\/span><\/a><span style=\"font-weight: 400\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POLITIQUE DE CONFIDENTIALIT\u00c9 ET COOKIES DU SITE WWW.CAMPINGS.COM. &nbsp; La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab\u00a0Politique de Confidentialit\u00e9\u00a0\u00bb) vise \u00e0 informer les utilisateurs du site www.campings.com (le \u00ab\u00a0Site\u00a0\u00bb) et clients (ensemble, les \u00ab\u00a0Utilisateurs\u00a0\u00bb) de la mani\u00e8re dont CAMPINGS.COM UNITED LTD (\u00ab\u00a0CAMPINGS.COM LTD\u00a0\u00bb) et les soci\u00e9t\u00e9s de son groupe, notamment CAMPINGS.COM SAS, traitent les informations se [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":15,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-onecolumn.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-12","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Politique de confidentialit\u00e9 et cookies - Campings FR BE Content<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Politique de confidentialit\u00e9 et cookies - Campings FR BE Content\" \/>\n<meta property=\"og:description\" content=\"POLITIQUE DE CONFIDENTIALIT\u00c9 ET COOKIES DU SITE WWW.CAMPINGS.COM. &nbsp; La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab\u00a0Politique de Confidentialit\u00e9\u00a0\u00bb) vise \u00e0 informer les utilisateurs du site www.campings.com (le \u00ab\u00a0Site\u00a0\u00bb) et clients (ensemble, les \u00ab\u00a0Utilisateurs\u00a0\u00bb) de la mani\u00e8re dont CAMPINGS.COM UNITED LTD (\u00ab\u00a0CAMPINGS.COM LTD\u00a0\u00bb) et les soci\u00e9t\u00e9s de son groupe, notamment CAMPINGS.COM SAS, traitent les informations se [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Campings FR BE Content\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-24T12:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"450\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"21 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/\",\"url\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/\",\"name\":\"Politique de confidentialit\u00e9 et cookies - Campings FR BE Content\",\"isPartOf\":{\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg\",\"datePublished\":\"2023-07-24T12:52:38+00:00\",\"dateModified\":\"2023-07-24T12:54:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#primaryimage\",\"url\":\"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg\",\"contentUrl\":\"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg\",\"width\":450,\"height\":300,\"caption\":\"Confidentialit\u00e9 et cookies\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.campings.com\/fr-be\/content\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Politique de confidentialit\u00e9 et cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.campings.com\/fr-be\/content\/#website\",\"url\":\"https:\/\/www.campings.com\/fr-be\/content\/\",\"name\":\"Campings FR BE Content\",\"description\":\"Just another Campings Blog Sites site\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.campings.com\/fr-be\/content\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Politique de confidentialit\u00e9 et cookies - Campings FR BE Content","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/","og_locale":"en_US","og_type":"article","og_title":"Politique de confidentialit\u00e9 et cookies - Campings FR BE Content","og_description":"POLITIQUE DE CONFIDENTIALIT\u00c9 ET COOKIES DU SITE WWW.CAMPINGS.COM. &nbsp; La pr\u00e9sente politique de confidentialit\u00e9 (la \u00ab\u00a0Politique de Confidentialit\u00e9\u00a0\u00bb) vise \u00e0 informer les utilisateurs du site www.campings.com (le \u00ab\u00a0Site\u00a0\u00bb) et clients (ensemble, les \u00ab\u00a0Utilisateurs\u00a0\u00bb) de la mani\u00e8re dont CAMPINGS.COM UNITED LTD (\u00ab\u00a0CAMPINGS.COM LTD\u00a0\u00bb) et les soci\u00e9t\u00e9s de son groupe, notamment CAMPINGS.COM SAS, traitent les informations se [&hellip;]","og_url":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/","og_site_name":"Campings FR BE Content","article_modified_time":"2023-07-24T12:54:42+00:00","og_image":[{"width":450,"height":300,"url":"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"21 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/","url":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/","name":"Politique de confidentialit\u00e9 et cookies - Campings FR BE Content","isPartOf":{"@id":"https:\/\/www.campings.com\/fr-be\/content\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#primaryimage"},"image":{"@id":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#primaryimage"},"thumbnailUrl":"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg","datePublished":"2023-07-24T12:52:38+00:00","dateModified":"2023-07-24T12:54:42+00:00","breadcrumb":{"@id":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#primaryimage","url":"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg","contentUrl":"https:\/\/www.campings.com\/fr-be\/content\/wp-content\/uploads\/sites\/5\/2023\/07\/hero-image-.jpeg","width":450,"height":300,"caption":"Confidentialit\u00e9 et cookies"},{"@type":"BreadcrumbList","@id":"https:\/\/www.campings.com\/fr-be\/content\/politique-de-confidentialite-et-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.campings.com\/fr-be\/content\/"},{"@type":"ListItem","position":2,"name":"Politique de confidentialit\u00e9 et cookies"}]},{"@type":"WebSite","@id":"https:\/\/www.campings.com\/fr-be\/content\/#website","url":"https:\/\/www.campings.com\/fr-be\/content\/","name":"Campings FR BE Content","description":"Just another Campings Blog Sites site","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.campings.com\/fr-be\/content\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/pages\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/comments?post=12"}],"version-history":[{"count":1,"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/pages\/12\/revisions"}],"predecessor-version":[{"id":14,"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/pages\/12\/revisions\/14"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/media\/15"}],"wp:attachment":[{"href":"https:\/\/www.campings.com\/fr-be\/content\/wp-json\/wp\/v2\/media?parent=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}